{"id":1637,"date":"2016-02-22T12:08:24","date_gmt":"2016-02-22T12:08:24","guid":{"rendered":"https:\/\/motors.stylemixthemes.com\/elementor-classified-one\/?page_id=1637"},"modified":"2016-02-22T12:08:24","modified_gmt":"2016-02-22T12:08:24","slug":"inventory","status":"publish","type":"page","link":"https:\/\/edonaujas.versify.digital\/lt\/inventory\/","title":{"rendered":"Inventorius"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1637\" class=\"elementor elementor-1637\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df633c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df633c6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-49a9402\" data-id=\"49a9402\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09e1328 elementor-widget elementor-widget-motors-inventory-search-filter\" data-id=\"09e1328\" data-element_type=\"widget\" data-widget_type=\"motors-inventory-search-filter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script type=\"text\/javascript\">\n\tvar rest_url = 'https:\/\/edonaujas.versify.digital\/lt\/wp-json\/stm_vehicles_listing\/v8';\n\tvar rest_key = 'f27334653021decdf87e40636b697e49e4bac757798e4bd0ae8cc7579ca4fe19a62d4063ae603109e4ba00791b4f350bae8cdecdc1adc1ad7e4961f4f720154034655c8ca5145f7c81538b001b4f8949873cae60246166ad200ddecd4bd0aa598b0061f40079e070873c412ee0706b69e4ba4063007995099437263d1b4ff7208b00decd6b69e4baa62de8367e4998098b00ae60e0709b988b0066ad6b69bfc8e83633111b4ff87ef720e07027472747';\n<\/script>\n<div class=\"sticky-mobile-filter\">\n\t<div class=\"mobile-filter\">\n\t\t<div class=\"mobile-search-btn icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"stm-icon-car_search\"><\/i>\t\t\t<span class=\"mobile-search-btn-text\">Paie\u0161kos parinktys<\/span>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"mobile-filter static-mobile-filter\">\n\t<div class=\"mobile-search-btn icon-left\">\n\t\t<i aria-hidden=\"true\" class=\"stm-icon-car_search\"><\/i>\t\t<span class=\"mobile-search-btn-text\">Paie\u0161kos parinktys<\/span>\n\t<\/div>\n<\/div>\n<div class=\"classic-filter-row motors-elementor-widget\">\n\t<form class=\"search-filter-form v8-inventory-form\" action=\"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637\/\" method=\"get\" data-trigger=\"filter\"\n\t\tdata-action=\"listings-result\" data-trp-original-action=\"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637\/\">\n\t\t<div class=\"filter filter-sidebar ajax-filter\">\n\t\t\t\t\t\t<div class=\"sidebar-entry-header icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"stm-icon-car_search\"><\/i>\t\t\t\t<span class=\"h4\">Paie\u0161kos parinktys<\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"sidebar-entry-header-mobile\">\n\t\t\t\t<span class=\"h4\">Paie\u0161kos parinktys<\/span>\n\t\t\t\t<div class=\"close-btn\">\n\t\t\t\t\t<span class=\"close-btn-item\"><\/span>\n\t\t\t\t\t<span class=\"close-btn-item\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"row row-pad-top-24\">\n\t\t\t\t\t\t\t\t\t<span id=\"stm_parent_slug_list\" class=\"hidden\" data-value=\"make\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_condition\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"condition\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tB\u016bsena\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"used-cars\"  >\n\t\t\t\tNaudotas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"new-cars\"  >\n\t\t\t\tNaujas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"certified-used\"   disabled='disabled'>\n\t\t\t\tSertifikuotas naudotas\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_body\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"body\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tTipai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"traktorius\"  >\n\t\t\t\tTraktoriai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"mini-krautuvai\"  >\n\t\t\t\tMINI KRAUTUVAI\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"teleskopiniai-krautuvai\"  >\n\t\t\t\tTeleskopiniai krautuvai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"automobiliai\"   disabled='disabled'>\n\t\t\t\tAutomobiliai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"kombainai\"   disabled='disabled'>\n\t\t\t\tKombainai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"motociklai\"   disabled='disabled'>\n\t\t\t\tMotociklai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"padargai\"   disabled='disabled'>\n\t\t\t\tPadargai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"traktorines-priekabos\"   disabled='disabled'>\n\t\t\t\tTraktorin\u0117s priekabos\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_make\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"make\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tMark\u0117\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"case-ih\"  >\n\t\t\t\tCase-IH\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"fendt\"  >\n\t\t\t\tFendt\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"massey-ferguson\"  >\n\t\t\t\tMassey Ferguson\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"new-holland\"  >\n\t\t\t\t\"New Holland\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"john-deere\"  >\n\t\t\t\t\"John Deere\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"kubota\"  >\n\t\t\t\tKubota\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"manitou\"  >\n\t\t\t\tManitou\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"mccormick\"  >\n\t\t\t\tMcCormick\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"volvo\"  >\n\t\t\t\tVOLVO\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"acura\"   disabled='disabled'>\n\t\t\t\tAcura\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"bentley\"   disabled='disabled'>\n\t\t\t\tBentley\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"bmw\"   disabled='disabled'>\n\t\t\t\tBMW\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"can-am\"   disabled='disabled'>\n\t\t\t\tCan-Am\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"chevrolet\"   disabled='disabled'>\n\t\t\t\tChevrolet\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"claas\"   disabled='disabled'>\n\t\t\t\tClaas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"ford\"   disabled='disabled'>\n\t\t\t\t\"Ford\"\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"honda\"   disabled='disabled'>\n\t\t\t\tHonda\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"hyundai\"   disabled='disabled'>\n\t\t\t\tHyundai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"jcb\"   disabled='disabled'>\n\t\t\t\tJcb\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"jeep\"   disabled='disabled'>\n\t\t\t\tD\u017eipas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"kia\"   disabled='disabled'>\n\t\t\t\tKia\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"lamborghini\"   disabled='disabled'>\n\t\t\t\tLamborghini\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"lexus\"   disabled='disabled'>\n\t\t\t\tLexus\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"mazda\"   disabled='disabled'>\n\t\t\t\tMazda\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"mercedes-benz\"   disabled='disabled'>\n\t\t\t\tMercedes\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"nissan\"   disabled='disabled'>\n\t\t\t\tNissan\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"tesla\"   disabled='disabled'>\n\t\t\t\tTesla\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"toyota\"   disabled='disabled'>\n\t\t\t\tToyota\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"volkswagen\"   disabled='disabled'>\n\t\t\t\tVolkswagen\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_serie\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"serie\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"make\" value=\"\"  >\n\t\t\t\tModelis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"0\"  >\n\t\t\t\t3645\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"6270-4\"  >\n\t\t\t\t6270-4\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"7430-premium-aq\"  >\n\t\t\t\t7430 Premium AQ\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"840-145-ps-elite\"  >\n\t\t\t\t840-145 PS ELITAS +\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"936-vario-profi\"  >\n\t\t\t\t936 Vario Profi\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"b8200-hst\"  >\n\t\t\t\tB8200 HST\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"cs-130\"  >\n\t\t\t\tcs 130\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"cs-150\"  >\n\t\t\t\tCS 150\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"favorit-512c\"  >\n\t\t\t\tFavorit 512C\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"m115\"  >\n\t\t\t\tM115\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"mc-115-t4\"  >\n\t\t\t\tMC 115 T4\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"mx-100c\"  >\n\t\t\t\tMX 100C\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"mx-170\"  >\n\t\t\t\tMX 170\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"puma-cvx-160\"  >\n\t\t\t\tPUMA CVX 160\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"ts-110\"  >\n\t\t\t\tTS 110\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"ztx-280\"  >\n\t\t\t\tZTX 280\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"1-series\"   disabled='disabled'>\n\t\t\t\t1 serija\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"2022-tucson\"   disabled='disabled'>\n\t\t\t\t2022 M. TUCSON\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"3-serie-model\"   disabled='disabled'>\n\t\t\t\t3 serijos\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"370z\"   disabled='disabled'>\n\t\t\t\t370Z\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"5-active\"   disabled='disabled'>\n\t\t\t\t5 Aktyvus\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"accord\"   disabled='disabled'>\n\t\t\t\tAccord\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"accord-2021\"   disabled='disabled'>\n\t\t\t\t\"Accord 2021\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"altima\"   disabled='disabled'>\n\t\t\t\tAltima\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"avalon\"   disabled='disabled'>\n\t\t\t\tAvalonas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"bentayaga\"   disabled='disabled'>\n\t\t\t\tBentayaga\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"bronco-2021\"   disabled='disabled'>\n\t\t\t\tBronco 2021\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"c-class\"   disabled='disabled'>\n\t\t\t\tC klas\u0117\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"camry\"   disabled='disabled'>\n\t\t\t\tCamry\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"civic\"   disabled='disabled'>\n\t\t\t\tPilietinis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"cr-v\"   disabled='disabled'>\n\t\t\t\tCR-V\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"cruze\"   disabled='disabled'>\n\t\t\t\tCruze\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"cx-5\"   disabled='disabled'>\n\t\t\t\tCX-5\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"e-class\"   disabled='disabled'>\n\t\t\t\tE klas\u0117\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"elantra\"   disabled='disabled'>\n\t\t\t\tElantra\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"es-300h\"   disabled='disabled'>\n\t\t\t\tES 300h\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"explorer\"   disabled='disabled'>\n\t\t\t\tExplorer\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"fhkt\"   disabled='disabled'>\n\t\t\t\tFhkt\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"flying-spur\"   disabled='disabled'>\n\t\t\t\t\"Flying Spur\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"focus\"   disabled='disabled'>\n\t\t\t\tFocus\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"g-class\"   disabled='disabled'>\n\t\t\t\tG klas\u0117\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"huracan\"   disabled='disabled'>\n\t\t\t\tHuracan\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"ilx-2021-limited-edition\"   disabled='disabled'>\n\t\t\t\tILX 2021 RIBOTAS LEIDIMAS\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"is-250-c\"   disabled='disabled'>\n\t\t\t\tIS 250 C\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"m440i\"   disabled='disabled'>\n\t\t\t\tM440i\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"m5\"   disabled='disabled'>\n\t\t\t\tM5\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"malibu\"   disabled='disabled'>\n\t\t\t\tMalibu\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"model-x\"   disabled='disabled'>\n\t\t\t\tX modelis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"mustang\"   disabled='disabled'>\n\t\t\t\tMustangas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"mx-5\"   disabled='disabled'>\n\t\t\t\tMX-5\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"pilot\"   disabled='disabled'>\n\t\t\t\tBandomasis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"rdx\"   disabled='disabled'>\n\t\t\t\tRDX\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"rdx-2015-se\"   disabled='disabled'>\n\t\t\t\tRDX 2015 SE\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"rio\"   disabled='disabled'>\n\t\t\t\tRio\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"rx-350\"   disabled='disabled'>\n\t\t\t\tRX 350\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"silverado\"   disabled='disabled'>\n\t\t\t\tSilverado\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"silverado-hd-2021\"   disabled='disabled'>\n\t\t\t\t\"Silverado HD 2021\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"sorento\"   disabled='disabled'>\n\t\t\t\t\"Sorento\"\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"soul\"   disabled='disabled'>\n\t\t\t\tSoul\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"suburban-2021\"   disabled='disabled'>\n\t\t\t\t2021 m. priemiestis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"tacoma\"   disabled='disabled'>\n\t\t\t\tTacoma\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"trailblazer-21\"   disabled='disabled'>\n\t\t\t\t\"Trailblazer 21\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"urus-2021\"   disabled='disabled'>\n\t\t\t\tUrus 2021\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"veloster\"   disabled='disabled'>\n\t\t\t\tVeloster\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"versa\"   disabled='disabled'>\n\t\t\t\tVersa\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"make\" value=\"x7-m50d\"   disabled='disabled'>\n\t\t\t\tX7 M50d\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_mileage\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"mileage\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tMax Motovalandos\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"&lt;1000\"  >\n\t\t\t\t&lt; 1000 \t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"1000-2000\"  >\n\t\t\t\t1000-2000 \t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"2000-5000\"  >\n\t\t\t\t2000-5000 \t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"5000-9000\"  >\n\t\t\t\t5000-9000 \t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"9000-12000\"  >\n\t\t\t\t9000-12000 \t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"&gt;12000\"  >\n\t\t\t\t&gt;12000 \t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_fuel\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"fuel\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tKuro tipas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"diesel\"  >\n\t\t\t\tDyzelinas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"electric\"   disabled='disabled'>\n\t\t\t\tElektrinis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"biofuels-biodiesel-and-bioethanol\"   disabled='disabled'>\n\t\t\t\tEtanolis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"fuel\"   disabled='disabled'>\n\t\t\t\tKuro\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"petrol\"   disabled='disabled'>\n\t\t\t\tBenzinas\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"premium-petrol\"   disabled='disabled'>\n\t\t\t\tHibridinis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"lpg-autogas\"   disabled='disabled'>\n\t\t\t\tSuskystint\u0173 duj\u0173 autodujos\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_ca-year\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"ca-year\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tMetai\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"0\"  >\n\t\t\t\t2000\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"1\"  >\n\t\t\t\t2017\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"2\"  >\n\t\t\t\t1991\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"3\"  >\n\t\t\t\t1997\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"4\"  >\n\t\t\t\t1998\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"5\"  >\n\t\t\t\t1999\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"6\"  >\n\t\t\t\t2002\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"7\"  >\n\t\t\t\t2003\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"8\"  >\n\t\t\t\t2006\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"9\"  >\n\t\t\t\t2009\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"10\"  >\n\t\t\t\t2010\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"11\"  >\n\t\t\t\t2013\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"12\"   disabled='disabled'>\n\t\t\t\t1967\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"13\"   disabled='disabled'>\n\t\t\t\t1990\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"14\"   disabled='disabled'>\n\t\t\t\t2005\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"15\"   disabled='disabled'>\n\t\t\t\t2007\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"16\"   disabled='disabled'>\n\t\t\t\t2008\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"17\"   disabled='disabled'>\n\t\t\t\t2011\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"18\"   disabled='disabled'>\n\t\t\t\t2012\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"19\"   disabled='disabled'>\n\t\t\t\t2014\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"20\"   disabled='disabled'>\n\t\t\t\t2015\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"21\"   disabled='disabled'>\n\t\t\t\t2016\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-6 stm-filter_transmission\">\n\t\t\t\t\t\t\t\t\t<div class=\"form-group type-select\">\n\t\t\t\t\t\t\t\t\t\t<select \t\t\tname=\"transmission\"\n\t\tclass=\"filter-select\" >\n\t\t\t\t<option data-parent=\"\" value=\"\"  >\n\t\t\t\tTransmisija\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"6-manual\"  >\n\t\t\t\tRankinis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"automatic\"  >\n\t\t\t\tAutomatinis\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"power-shift\"  >\n\t\t\t\t\"Power Shift\t\t\t<\/option>\n\t\t\t\t\t\t<option data-parent=\"\" value=\"semi-manual\"   disabled='disabled'>\n\t\t\t\tPusiau automatinis\t\t\t<\/option>\n\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-12 stm-filter_listing_status\">\n\t\t\t\t\t\t\t<div class=\"form-group\">\n\t\t\t\t\t\t\t\t<select name=\"listing_status\" class=\"form-control\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">\n\t\t\t\t\t\t\t\t\t\tListing status\t\t\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"active\" >\n\t\t\t\t\t\t\t\t\t\tActive\t\t\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"sold\" >\n\t\t\t\t\t\t\t\t\t\tSold\t\t\t\t\t\t\t\t\t<\/option>\n\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<!--Location inputs-->\n\n\n\t\t\t\t\t\t\t<div class=\"col-md-12 col-sm-12 stm-search_keywords\">\n\t\t<div class=\"form-group type-text\">\n\t\t\t\t\t\t\t<h5>Search by keywords<\/h5>\n\t\t\t\t\t\t<input type=\"text\" class=\"form-control\" name=\"stm_keywords\" placeholder=\"Search...\" id=\"stm_keywords\" value=\"\" aria-label=\"Search by keywords in listings\">\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!--View type-->\n\t\t\t<input type=\"hidden\" id=\"stm_view_type\" name=\"view_type\"\n\t\t\t\tvalue=\"\"\/>\n\t\t\t<!--Filter links-->\n\t\t\t<input type=\"hidden\" id=\"stm-filter-links-input\" name=\"stm_filter_link\" value=\"\"\/>\n\t\t\t<!--Popular-->\n\t\t\t<input type=\"hidden\" name=\"popular\" value=\"\"\/>\n\n\t\t\t<input type=\"hidden\" name=\"s\" value=\"\"\/>\n\t\t\t<input type=\"hidden\" name=\"sort_order\"\n\t\t\t\tvalue=\"\"\/>\n\n\t\t\t<div class=\"sidebar-action-units\">\n\t\t\t\t<input id=\"stm-classic-filter-submit\" class=\"hidden\" type=\"submit\"\n\t\t\t\t\tvalue=\"Show cars\"\/>\n\n\t\t\t\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/inventory\/\" class=\"button\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-undo\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M212.333 224.333H12c-6.627 0-12-5.373-12-12V12C0 5.373 5.373 0 12 0h48c6.627 0 12 5.373 12 12v78.112C117.773 39.279 184.26 7.47 258.175 8.007c136.906.994 246.448 111.623 246.157 248.532C504.041 393.258 393.12 504 256.333 504c-64.089 0-122.496-24.313-166.51-64.215-5.099-4.622-5.334-12.554-.467-17.42l33.967-33.967c4.474-4.474 11.662-4.717 16.401-.525C170.76 415.336 211.58 432 256.333 432c97.268 0 176-78.716 176-176 0-97.267-78.716-176-176-176-58.496 0-110.28 28.476-142.274 72.333h98.274c6.627 0 12 5.373 12 12v48c0 6.627-5.373 12-12 12z\"><\/path><\/svg>\t\t\t\t\t<span>I\u0161 naujo nustatyti visk\u0105<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<!--Classified price-->\n\t\t\n<div class=\"stm-filter-listing-directory-price\">\n\t<div class=\"stm-accordion-single-unit price\">\n\t\t<a class=\"title\" data-toggle=\"collapse\" href=\"#price\" aria-expanded=\"true\">\n\t\t\t<h5>Select Price<\/h5>\n\t\t\t<span class=\"minus\"><\/span>\n\t\t<\/a>\n\t\t<div class=\"stm-accordion-content collapse in content\" id=\"price\">\n\t\t\t<div class=\"stm-accordion-content-wrapper\">\n\t\t\t\t<div class=\"stm-price-range-unit\">\n\t\t\t\t\t<div class=\"stm-price-range\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-md-6 col-sm-6 col-md-wider-right\">\n\t\t\t\t\t\t<input type=\"text\" name=\"min_price\" id=\"stm_filter_min_price\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-md-6 col-sm-6 col-md-wider-left\">\n\t\t\t\t\t\t<input type=\"text\" name=\"max_price\" id=\"stm_filter_max_price\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<!--Init slider-->\n\n<script type=\"text\/javascript\">\n\tvar stmOptions_price;\n\t(function ($) {\n\t\t$(document).ready(function () {\n\t\t\tvar affix = \"\";\n\t\t\tvar stmMinValue = 5000;\n\t\t\tvar stmMaxValue = 300000;\n\t\t\tstmOptions_price = {\n\t\t\t\trange: true,\n\t\t\t\tmin: 5000,\n\t\t\t\tmax: 300000,\n\t\t\t\tvalues: [5000, 300000],\n\t\t\t\tstep: 100,\n\t\t\t\tslide: function (event, ui) {\n\t\t\t\t\t$(\"#stm_filter_min_price\").val(ui.values[0]);\n\t\t\t\t\t$(\"#stm_filter_max_price\").val(ui.values[1]);\n\t\t\t\t\t\t\t\t\t\tvar stmCurrency = \"\u20ac\";\n\t\t\t\t\tvar stmPriceDel = \" \";\n\t\t\t\t\tvar stmCurrencyPos = \"right\";\n\t\t\t\t\tvar stmText = stm_get_price_view(ui.values[0], stmCurrency, stmCurrencyPos, stmPriceDel ) + ' - ' + stm_get_price_view(ui.values[1], stmCurrency, stmCurrencyPos, stmPriceDel );\n\t\t\t\t\t\n\t\t\t\t\t$('.filter-price .stm-current-slider-labels').html(stmText);\n\t\t\t\t}\n\t\t\t};\n\t\t\t$(\".stm-price-range\").slider(stmOptions_price);\n\n\n\t\t\t$(\"#stm_filter_min_price\").val($(\".stm-price-range\").slider(\"values\", 0));\n\t\t\t$(\"#stm_filter_max_price\").val($(\".stm-price-range\").slider(\"values\", 1));\n\n\t\t\t$(\"#stm_filter_min_price\").on('keyup', function () {\n\t\t\t\t$(\".stm-price-range\").slider(\"values\", 0, $(this).val());\n\t\t\t});\n\n\t\t\t$(\"#stm_filter_min_price\").on('focusout', function () {\n\t\t\t\tif ($(this).val() < stmMinValue) {\n\t\t\t\t\t$(\".stm-price-range\").slider(\"values\", 0, stmMinValue);\n\t\t\t\t\t$(this).val(stmMinValue);\n\t\t\t\t}\n\t\t\t});\n\n\t\t\t$(\"#stm_filter_max_price\").on('keyup', function () {\n\t\t\t\t$(\".stm-price-range\").slider(\"values\", 1, $(this).val());\n\t\t\t});\n\n\t\t\t$(\"#stm_filter_max_price\").on('focusout', function () {\n\t\t\t\tif ($(this).val() > stmMaxValue) {\n\t\t\t\t\t$(\".stm-price-range\").slider(\"values\", 1, stmMaxValue);\n\t\t\t\t\t$(this).val(stmMaxValue);\n\t\t\t\t}\n\t\t\t});\n\t\t})\n\t})(jQuery);\n<\/script>\n\t\t\t\t\t\t<div class=\"grow-wrapper\"><\/div>\n\t\t<div class=\"sticky-filter-actions\">\n\t\t\t<div class=\"filter-show-cars\">\n\t\t\t\t<button id=\"show-car-btn-mobile\" class=\"show-car-btn\">\n\t\t\t\t\tShow <span>16<\/span> Cars\t\t\t\t\t<\/button>\n\t\t\t<\/div>\n\t\t\t<div class=\"reset-btn-mobile\">\n\t\t\t\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/inventory\/\" class=\"button\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-undo\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M212.333 224.333H12c-6.627 0-12-5.373-12-12V12C0 5.373 5.373 0 12 0h48c6.627 0 12 5.373 12 12v78.112C117.773 39.279 184.26 7.47 258.175 8.007c136.906.994 246.448 111.623 246.157 248.532C504.041 393.258 393.12 504 256.333 504c-64.089 0-122.496-24.313-166.51-64.215-5.099-4.622-5.334-12.554-.467-17.42l33.967-33.967c4.474-4.474 11.662-4.717 16.401-.525C170.76 415.336 211.58 432 256.333 432c97.268 0 176-78.716 176-176 0-97.267-78.716-176-176-176-58.496 0-110.28 28.476-142.274 72.333h98.274c6.627 0 12 5.373 12 12v48c0 6.627-5.373 12-12 12z\"><\/path><\/svg>\t\t\t\t\t<span>I\u0161 naujo nustatyti visk\u0105<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<input type=\"hidden\" name=\"trp-form-language\" value=\"lt\"\/><\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-d5e7248\" data-id=\"d5e7248\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f6180c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f6180c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c6bf60b\" data-id=\"c6bf60b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a198b1e elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"a198b1e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 29-01-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Parduodami automobiliai<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0f760f6\" data-id=\"0f760f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2c95b elementor-widget elementor-widget-motors-inventory-sort-by\" data-id=\"4b2c95b\" data-element_type=\"widget\" data-widget_type=\"motors-inventory-sort-by.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"stm-sort-by-options clearfix\">\n\t<span>Sort by:<\/span>\n\t<div class=\"stm-select-sorting\">\n\t\t<select>\n\t\t\t<option value=\"date_high\" selected>Date: newest first<\/option><option value=\"date_low\">Date: oldest first<\/option><option value=\"mileage_high\">Motovalandos: highest first<\/option><option value=\"mileage_low\">Motovalandos: lowest first<\/option><option value=\"engine_high\">Arklio galios: highest first<\/option><option value=\"engine_low\">Arklio galios: lowest first<\/option><option value=\"price_high\">Kaina: highest first<\/option><option value=\"price_low\">Kaina: lowest first<\/option><option value=\"fuel-consumption_high\">Fuel consumption: highest first<\/option><option value=\"fuel-consumption_low\">Fuel consumption: lowest first<\/option><option value=\"fuel-economy_high\">Fuel economy: highest first<\/option><option value=\"fuel-economy_low\">Fuel economy: lowest first<\/option>\t\t<\/select>\n\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0dd5c81\" data-id=\"0dd5c81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57741f elementor-widget elementor-widget-motors-inventory-view-type\" data-id=\"b57741f\" data-element_type=\"widget\" data-widget_type=\"motors-inventory-view-type.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"stm-view-by\">\n\t<a href=\"#\" class=\"view-grid view-type active\" data-view=\"grid\">\n\t\t<i class=\"stm-icon-grid\"><\/i>\n\t<\/a>\n\t<a href=\"#\" class=\"view-list view-type\" data-view=\"list\">\n\t\t<i class=\"stm-icon-list\"><\/i>\n\t<\/a>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb618df elementor-widget elementor-widget-motors-inventory-search-results\" data-id=\"bb618df\" data-element_type=\"widget\" data-widget_type=\"motors-inventory-search-results.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"motors-elementor-inventory-search-results\" id=\"listings-result\">\n\t\n\t<div class=\"stm-isotope-sorting stm-isotope-sorting-grid\">\n\t\t\t\t<div class=\"row row-3 car-listing-row car-listing-modern-grid\">\n\t\t\t\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2000-61 new-holland-269 power-shift-303 traktorius-272 ts-110-304 used-cars-247 listing_is_active\"\n\tdata-price=\"17800\"\n\tdata-date=\"202402040843\"\n\tdata-mileage=\"\t6079\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/new-holland-ts-110-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 New Holland TS 110\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-6-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-6-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-6-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 New Holland TS 110\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-5-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-5-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-5-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 New Holland TS 110\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-3-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-3-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-3-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 New Holland TS 110\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t4 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-7-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-7-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-7-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 New Holland TS 110\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92782 stm-car-photos-92782-44\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>9<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92782-44\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-5.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-5.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-3.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-3.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-7.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-7.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-18.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-18.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-10.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-10.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-13.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-13.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-ts-110-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92782\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92782\"\n\t\t\tdata-title=\"Used 2000 New Holland TS 110\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">17 800\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2000 m. New Holland TS 110\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>6079 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\"Power Shift<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 1997-302 diesel-131 m115-301 new-holland-269 power-shift-303 traktorius-272 used-cars-247 listing_is_active\"\n\tdata-price=\"24200\"\n\tdata-date=\"202402040834\"\n\tdata-mileage=\"\t9800\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/new-holland-m115-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1997 New Holland M115\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1997 New Holland M115\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1997 New Holland M115\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-4-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-4-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-4-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1997 New Holland M115\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t4 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-13-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-13-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-13-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1997 New Holland M115\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92771 stm-car-photos-92771-80\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>9<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92771-80\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-4.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-4.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-13.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-13.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-12.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-12.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-9.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-9.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-14.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-14.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-18.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/new-holland-m-115-135-traktoriai-18.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92771\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92771\"\n\t\t\tdata-title=\"Used 1997 New Holland M115\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">24 200\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 1997 m. New Holland M115\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>9800 myli\u0173<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\"Power Shift<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2017-288 automatic-102 diesel-131 mc-115-t4-299 mini-krautuvai-300 used-cars-247 volvo-298 listing_is_active\"\n\tdata-price=\"28600\"\n\tdata-date=\"202402040826\"\n\tdata-mileage=\"\t1914\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/volvo-mc-115-t4-mini-krautuvai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2017 VOLVO MC 115 T4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2017 VOLVO MC 115 T4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2017 VOLVO MC 115 T4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-6-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-6-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-6-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2017 VOLVO MC 115 T4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t6 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-14-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-14-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-14-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2017 VOLVO MC 115 T4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92760 stm-car-photos-92760-37\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>11<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92760-37\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-14.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-14.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-19.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-19.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-21.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-21.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-23.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-23.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-10.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-10.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-16.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/volvo-mc-115-t4-mini-krautuvai-16.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t\t\t<div class=\"stm-listing-videos-unit stm-car-videos-92760 stm-car-videos-92760-37\">\n\t\t\t\t<i class=\"fas fa-film\"><\/i>\n\t\t\t\t<span>1<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\n\t\t\t\t\tjQuery(\".stm-car-videos-92760-37\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/youtube.com\/shorts\/RE79zIcon7M?si=d1OFI8LFNotXKw5R\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t}); \/\/click\n\t\t\t\t}); \/\/ready\n\n\t\t\t<\/script>\n\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92760\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92760\"\n\t\t\tdata-title=\"Used 2017 VOLVO MC 115 T4\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">28 600\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2017 m. VOLVO MC 115 T4\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>1914 mi<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Automatinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 1991-297 3645-296 diesel-131 6-manual-175 massey-ferguson-268 traktorius-272 used-cars-247 listing_is_active\"\n\tdata-price=\"16801\"\n\tdata-date=\"202402040821\"\n\tdata-mileage=\"\t7654\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/massey-ferguson-3645-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1991 Massey Ferguson 3645\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1991 Massey Ferguson 3645\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-6-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-6-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-6-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1991 Massey Ferguson 3645\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-7-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-7-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-7-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1991 Massey Ferguson 3645\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t6 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-12-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-12-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-12-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 1991 Massey Ferguson 3645\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92746 stm-car-photos-92746-26\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>11<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92746-26\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-7.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-7.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-12.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-12.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-8.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-8.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-9.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-9.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-13.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-13.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-14.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-14.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-15.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-3645-traktoriai-15.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t\t\t<div class=\"stm-listing-videos-unit stm-car-videos-92746 stm-car-videos-92746-2\">\n\t\t\t\t<i class=\"fas fa-film\"><\/i>\n\t\t\t\t<span>1<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\n\t\t\t\t\tjQuery(\".stm-car-videos-92746-2\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/youtube.com\/shorts\/zZV22yyrNeQ?si=w7YrJnwhLsS5kIhF\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t}); \/\/click\n\t\t\t\t}); \/\/ready\n\n\t\t\t<\/script>\n\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92746\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92746\"\n\t\t\tdata-title=\"Used 1991 Massey Ferguson 3645\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">16 801\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 1991 m. Massey Ferguson 3645\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>7654 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Rankinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2000-61 6270-4-295 diesel-131 6-manual-175 massey-ferguson-268 traktorius-272 used-cars-247 listing_is_active\"\n\tdata-price=\"18700\"\n\tdata-date=\"202402040817\"\n\tdata-mileage=\"\t\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/massey-ferguson-6270-4-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 Massey Ferguson 6270-4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 Massey Ferguson 6270-4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-3-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-3-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-3-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 Massey Ferguson 6270-4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 Massey Ferguson 6270-4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t4 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-4-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-4-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-4-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2000 Massey Ferguson 6270-4\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92733 stm-car-photos-92733-80\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>9<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92733-80\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-3.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-3.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-4.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-4.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-5.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-5.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-7.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-7.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/massey-ferguson-6270-4-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t\t\t<div class=\"stm-listing-videos-unit stm-car-videos-92733 stm-car-videos-92733-49\">\n\t\t\t\t<i class=\"fas fa-film\"><\/i>\n\t\t\t\t<span>1<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\n\t\t\t\t\tjQuery(\".stm-car-videos-92733-49\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/youtube.com\/shorts\/xzfn_tLod-I?si=STbVbcWkJ0m8bPj6\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t}); \/\/click\n\t\t\t\t}); \/\/ready\n\n\t\t\t<\/script>\n\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92733\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92733\"\n\t\t\tdata-title=\"Used 2000 Massey Ferguson 6270-4\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">18 700\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2000 m. Massey Ferguson 6270-4\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Rankinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2006-65 automatic-102 diesel-131 mccormick-261 traktorius-272 used-cars-247 ztx-280-294 listing_is_active\"\n\tdata-price=\"28400\"\n\tdata-date=\"202402040813\"\n\tdata-mileage=\"\t6222\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/mccormick-ztx-280-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2006 McCormick ZTX 280\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2006 McCormick ZTX 280\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2006 McCormick ZTX 280\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-3-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-3-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-3-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2006 McCormick ZTX 280\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t3 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-6-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-6-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-6-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2006 McCormick ZTX 280\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92722 stm-car-photos-92722-38\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>8<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92722-38\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-3.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-3.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-10.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-10.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-8.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/mccormick-ztx-280-traktoriai-8.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92722\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92722\"\n\t\t\tdata-title=\"Used 2006 McCormick ZTX 280\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">28 400\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2006 m. McCormick ZTX 280\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>6222 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Automatinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2009-68 936-vario-profi-293 automatic-102 fendt-260 traktorius-272 used-cars-247 listing_is_sold\"\n\tdata-price=\"62500\"\n\tdata-date=\"202402040808\"\n\tdata-mileage=\"\t11563\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/fendt-936-vario-profi-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2009 Fendt 936 Vario Profi\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-3-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-3-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-3-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2009 Fendt 936 Vario Profi\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-6-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-6-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-6-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2009 Fendt 936 Vario Profi\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-14-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-14-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-14-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2009 Fendt 936 Vario Profi\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t5 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-8-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-8-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-8-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2009 Fendt 936 Vario Profi\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"stm-badge-directory heading-font\" style=\"background-color:#fc4e4e;\">\n\t\t\tSold\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92712 stm-car-photos-92712-94\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>10<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92712-94\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-3.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-3.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-6.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-6.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-14.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-14.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-8.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-8.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-15.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-15.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-17.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-17.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-20.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-20.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-22.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/fendt-936-vario-traktoriai-22.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92712\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92712\"\n\t\t\tdata-title=\"Used 2009 Fendt 936 Vario Profi\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">62 500\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2009 m. Fendt 936 Vario Profi\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>11563 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Automatinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2003-292 case-ih-262 cs-130-291 6-manual-175 traktorius-272 used-cars-247 listing_is_active\"\n\tdata-price=\"24002\"\n\tdata-date=\"202402040803\"\n\tdata-mileage=\"\t6152\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/case-ih-cs-130-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-0-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-0-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-0-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2003 Case-IH cs 130\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2003 Case-IH cs 130\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2003 Case-IH cs 130\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-10-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-10-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-10-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2003 Case-IH cs 130\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t3 more photos\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-5-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-5-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-5-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2003 Case-IH cs 130\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92700 stm-car-photos-92700-43\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>8<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92700-43\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-0.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-0.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-10.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-10.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-5.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-5.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-14.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-14.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-15.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-15.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-16.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs130-traktoriai-16.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92700\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92700\"\n\t\t\tdata-title=\"Used 2003 Case-IH cs 130\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">24 002\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2003 m. Case-IH cs 130\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>6152 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Rankinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\n<div\n\tclass=\"col-md-4 col-sm-4 col-xs-12 col-xxs-12  stm-directory-grid-loop stm-isotope-listing-item all 2002-290 case-ih-262 cs-150-289 diesel-131 6-manual-175 traktorius-272 used-cars-247 listing_is_active\"\n\tdata-price=\"24499\"\n\tdata-date=\"202402040759\"\n\tdata-mileage=\"\t8506\">\n\t<a href=\"https:\/\/edonaujas.versify.digital\/lt\/listings\/case-ih-cs-150-traktoriai-used\/\" class=\"rmv_txt_drctn\">\n\n<div class=\"image\">\n\t\t\t\t\t<div class=\"interactive-hoverable\">\n\t\t\t\t\t<div class=\"hoverable-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit active\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-0-2-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-0-2-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-0-2-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2002 Case-IH CS 150\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-1-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-1-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-1-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2002 Case-IH CS 150\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-5-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-5-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-5-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2002 Case-IH CS 150\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-7-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-7-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-7-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2002 Case-IH CS 150\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"hoverable-unit\">\n\t\t\t\t\t\t\t\t<div class=\"thumb\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"remaining\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-album\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\t\t\t1 more photo\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img\n\t\t\t\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-9-255x160.jpg\"\n\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-9-255x160.jpg 1x, https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-9-510x320.jpg 2x\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"img-responsive\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\t\t\t\t\t\t\talt=\"Used 2002 Case-IH CS 150\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"hoverable-indicators\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator active\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"indicator\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t<!---Media-->\n\t<div class=\"stm-car-medias\">\n\t\t\t\t\t<div class=\"stm-listing-photos-unit stm-car-photos-92689 stm-car-photos-92689-5\">\n\t\t\t\t<i class=\"stm-service-icon-photo\"><\/i>\n\t\t\t\t<span>6<\/span>\n\t\t\t<\/div>\n\n\t\t\t<script>\n\t\t\t\tjQuery(document).ready(function(){\n\t\t\t\t\tjQuery(\".stm-car-photos-92689-5\").on('click', function(e) {\n\t\t\t\t\t\te.preventDefault();\n\t\t\t\t\t\tjQuery(this).lightGallery({\n\t\t\t\t\t\t\tdynamic: true,\n\t\t\t\t\t\t\tdynamicEl: [\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-0-2.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-0-2.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-1.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-1.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-5.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-5.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-7.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-7.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-9.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-9.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\tsrc  : \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-11.jpg\",\n\t\t\t\t\t\t\t\t\tthumb: \"https:\/\/edonaujas.versify.digital\/wp-content\/uploads\/2024\/02\/case-ih-cs-150-traktoriai-11.jpg\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t],\n\t\t\t\t\t\t\tdownload: false,\n\t\t\t\t\t\t\tmode: 'lg-fade',\n\t\t\t\t\t\t})\n\t\t\t\t\t});\n\t\t\t\t});\n\n\t\t\t<\/script>\n\t\t\t\t\t<\/div>\n\n\t<!--Favorite-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-favorite\"\n\t\t\tdata-id=\"92689\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"right\"\n\t\t\ttitle=\"Add to favorites\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-staricon\"><\/i>\n\t\t<\/div>\n\t\n\t<!--Compare-->\n\t\t\t<div\n\t\t\tclass=\"stm-listing-compare stm-compare-directory-new\"\n\t\t\tdata-post-type=\"listings\"\n\t\t\tdata-id=\"92689\"\n\t\t\tdata-title=\"Used 2002 Case-IH CS 150\"\n\t\t\tdata-toggle=\"tooltip\" data-placement=\"left\"\n\t\t\ttitle=\"Add to compare\"\n\t\t>\n\t\t\t<i class=\"stm-service-icon-compare-new\"><\/i>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"listing-car-item-meta\">\n\t<div class=\"car-meta-top heading-font clearfix\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"price\">\n\t\t\t\t\t<div class=\"normal-price\">24 499\u20ac<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"car-title\" data-max-char=\"44\">\n\t\tNaudotas 2002 m. Case-IH CS 150\t<\/div>\n<\/div>\n\n\t\t<div class=\"car-meta-bottom\">\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-road\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span>8506 mylios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"stm-icon-transmission_fill\"><\/i>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Rankinis<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\n<\/div>\n<\/a>\n<\/div>\n\t\t<\/div>\n\t\n\t<\/div>\n\t\t<div class=\"stm_ajax_pagination stm-blog-pagination\">\n\t\t<ul class='page-numbers'>\n\t<li><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637\/page\/2\/\">2<\/a><\/li>\n\t<li><a class=\"next page-numbers\" href=\"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637\/page\/2\/\"><i class=\"fas fa-angle-right\"><\/i><\/a><\/li>\n<\/ul>\n\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a975c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a975c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de1bf9a\" data-id=\"de1bf9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Search Options Search Options Search Options Condition Certified Used New Used Body Compact Convertible Coupe Hatchback Minivan Off-Road Pickups Sedan Sport Cars SUV Wagon Make Acura Bentley BMW Chevrolet Ford Honda Hyundai Jeep Kia Lamborghini Lexus Mazda Mercedes Nissan Tesla Toyota Volkswagen Model 1 Series 2022 TUCSON 3 Series 370Z 5 Active Accord Accord 2021&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637"}],"collection":[{"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":0,"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/pages\/1637\/revisions"}],"wp:attachment":[{"href":"https:\/\/edonaujas.versify.digital\/lt\/wp-json\/wp\/v2\/media?parent=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}